{"id":29866,"date":"2025-12-17T10:30:16","date_gmt":"2025-12-17T08:30:16","guid":{"rendered":"https:\/\/theisraelbible.com\/la-comunidad-judia-de-2-000-anos-de-antiguedad\/"},"modified":"2025-12-22T14:20:15","modified_gmt":"2025-12-22T12:20:15","slug":"la-comunidad-judia-de-2-000-anos-de-antiguedad","status":"publish","type":"post","link":"https:\/\/theisraelbible.com\/es\/la-comunidad-judia-de-2-000-anos-de-antiguedad\/","title":{"rendered":"La comunidad jud\u00eda de 2.000 a\u00f1os de antig\u00fcedad"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Imag\u00ednate esto: est\u00e1s llevando a tus hijos al colegio, o tal vez vas de camino a hacer la compra. A tu derecha, ves las colinas verdes de siempre. Pero entonces, a tu izquierda, algo te llama la atenci\u00f3n. No es otra casa ni una valla publicitaria, sino las ruinas de una antigua sinagoga de hace m\u00e1s de 2.000 a\u00f1os. \u00ab\u00a1Mam\u00e1!\u00bb, grita una voz desde el asiento trasero. \u00ab\u00bfMe das un bocadillo?\u00bb Un d\u00eda m\u00e1s en Israel, donde la historia antigua y la vida cotidiana se mezclan a la perfecci\u00f3n.      <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No es una escena inventada. Es una experiencia real que puedes tener mientras conduces cerca de Modi&#8217;in, una ciudad del centro de Israel. Aqu\u00ed, un yacimiento arqueol\u00f3gico llamado Umm El Umdan descansa tranquilamente entre edificios modernos, guardando secretos de la \u00e9poca de los macabeos, los mismos h\u00e9roes que celebramos durante Januc\u00e1.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, \u00bfqu\u00e9 hace tan especial a este viejo mont\u00f3n de piedras? Hagamos un viaje en el tiempo para averiguarlo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacia el a\u00f1o 167 a.C., la tierra de Israel estaba gobernada por los sel\u00e9ucidas. Quer\u00edan que todo el mundo siguiera las costumbres griegas y adorara a los dioses griegos. Pero muchos jud\u00edos no estaban de acuerdo con esto. En una ciudad llamada Modi&#8217;in, un sacerdote jud\u00edo llamado Matat\u00edas se enfrent\u00f3 a los soldados sel\u00e9ucidas. Este valiente acto estuvo marcado por un poderoso grito de guerra que recordaba a una llamada b\u00edblica anterior: \u00ab\u05de\u05d9 \u05dc\u05d4&#8217; \u05d0\u05dc\u05d9\u00bb-\u00abQuien est\u00e9 por el Se\u00f1or, que venga a m\u00ed\u00bb. Esta declaraci\u00f3n se hac\u00eda eco de las palabras de Mois\u00e9s en \u00c9xodo 32:26:     <\/p>\n\n\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/exodus-32\/#verse_26\"><blockquote><p class=\"short_hebrew\">\u05d5\u05b7\u05d9\u05bc\u05b7\u05e2\u05b2\u05de\u05b9\u05d3 \u05de\u05b9\u05e9\u05c1\u05b6\u05d4 \u05d1\u05bc\u05b0\u05e9\u05c1\u05b7\u05e2\u05b7\u05e8 \u05d4\u05b7\u05de\u05bc\u05b7\u05d7\u05b2\u05e0\u05b6\u05d4 \u05d5\u05b7\u05d9\u05bc\u05b9\u05d0\u05de\u05b6\u05e8 \u05de\u05b4\u05d9 \u05dc\u05b7\u05d9\u05d4\u05b9\u05d5\u05b8\u05d4 \u05d0\u05b5\u05dc\u05b8\u05d9 \u05d5\u05b7\u05d9\u05bc\u05b5\u05d0\u05b8\u05e1\u05b0\u05e4\u05d5\u05bc \u05d0\u05b5\u05dc\u05b8\u05d9\u05d5 \u05db\u05bc\u05b8\u05dc\u05be\u05d1\u05bc\u05b0\u05e0\u05b5\u05d9 \u05dc\u05b5\u05d5\u05b4\u05d9\u05c3<\/p><p class=\"short_transliteration\">vai-YA-a-MOD mo-SHEH b&#8217;-sha-AR ha-ma-kha-NEH, va-YO-mer, mee la-a-do-NAI e-LAI, va-y&#8217;-a-S&#8217;-fu e-LAV kol b&#8217;-NAY l&#8217;-VI<\/p><p class=\"short_translation\"><em>Moshe<\/em> se levant\u00f3 en la puerta del campamento y dijo: \u00ab\u00a1Quien est\u00e9 por <em>Hashem<\/em>, venga aqu\u00ed!\u00bb Y todos los <em>Leviim<\/em> se unieron a \u00e9l.<\/p><figcaption><cite>\u00c9xodo 32:26<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n\n\n<p class=\"wp-block-paragraph\">  Con estas palabras, Matat\u00edas encendi\u00f3 una rebeli\u00f3n dirigida por \u00e9l y sus hijos, que se conocieron como los Macabeos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La historia de esta rebeli\u00f3n se relata en textos antiguos. Uno de ellos, llamado 1 Macabeos, dice: \u00abEn aquellos d\u00edas Matat\u00edas hijo de Juan, hijo de Sime\u00f3n, sacerdote de la familia de Joarib, se traslad\u00f3 de Jerusal\u00e9n y se estableci\u00f3 en Modein\u00bb. Por supuesto, esto sit\u00faa a Modi&#8217;in justo en el centro de la historia de Januc\u00e1.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avance r\u00e1pido hasta hoy. Entre 2000 y 2023, los arque\u00f3logos descubrieron algo asombroso: las ruinas de una antigua aldea, posiblemente el mismo lugar donde vivieron Matat\u00edas y los Macabeos. La llaman Umm El Umdan, que muchos creen que era una versi\u00f3n antigua de la ciudad actual de \u00abModi&#8217;in\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los descubrimientos m\u00e1s interesantes que desenterraron fue una antigua sinagoga. No se parec\u00eda exactamente a las sinagogas actuales. No hab\u00eda arca (el armario donde se guardan los rollos de la Tor\u00e1). En su lugar, creen que la gente llevaba los rollos de la Tor\u00e1 a la sinagoga cuando los necesitaba. En el centro de la sala hab\u00eda una gran piedra que probablemente se utilizaba como mesa para leer la Tor\u00e1. Alrededor de las paredes hab\u00eda bancos de piedra donde se sentaba la gente.     <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cerca de la sinagoga, encontraron lo que podr\u00eda haber sido una escuela. Esto concuerda con lo que sabemos por antiguos escritos jud\u00edos, que dicen que por esta \u00e9poca, un rabino llamado Yehoshua ben Gamla dijo que todos los ni\u00f1os jud\u00edos deb\u00edan ir a la escuela a partir de los seis a\u00f1os. Para m\u00ed, esto tiene un significado adicional: la escuela actual de mi hijo est\u00e1 a la vuelta de la esquina de una que es 2.000 a\u00f1os m\u00e1s antigua.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los arque\u00f3logos tambi\u00e9n encontraron casas, algunas incluso de dos plantas. Descubrieron dep\u00f3sitos de agua, hornos y lugares donde se elaboraba vino y aceite de oliva. Algo muy importante que encontraron fue una mikvah <em>, una<\/em>piscina especial utilizada para el ba\u00f1o ritual en el juda\u00edsmo. Encontrar una <em>mikvah <\/em>nos dice que la gente que viv\u00eda all\u00ed se preocupaba mucho por seguir las leyes y tradiciones jud\u00edas.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caminando por las ruinas de esta antigua ciudad, sientes el tejido de la vida que te rodea. Puedes imaginarte las luchas y contiendas de los macabeos mientras luchaban por la soberan\u00eda religiosa en su propio pa\u00eds. \u00ab\u05de\u05d9 \u05dc\u05d4&#8217; \u05d0\u05dc\u05d9\u00bb-\u00abQuien est\u00e9 por el Se\u00f1or, que venga a m\u00ed\u00bb. La llamada que inici\u00f3 una revoluci\u00f3n y los rituales cotidianos que dieron forma a una comunidad se entretejen en este paisaje hist\u00f3rico.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Israel es una tierra donde coexisten la historia y el presente, y el legado de los macabeos sigue inspir\u00e1ndonos. Su llamamiento a defender lo que es justo, su dedicaci\u00f3n a sus creencias y su perdurable impacto en la tradici\u00f3n jud\u00eda resuenan en cada piedra e historia que transmitimos a la siguiente generaci\u00f3n. <\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/keepgodsland.com\/\"><em>Mantengamos la Tierra de Dios<\/em><\/a><em> se dedica a fortalecer y defender el derecho de Israel a su coraz\u00f3n b\u00edblico. <\/em><a href=\"https:\/\/keepgodsland.com\/\"><em>Inf\u00f3rmate hoy mismo sobre esta incre\u00edble misi\u00f3n.<\/em><\/a><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Israel es una tierra donde coexisten la historia y el presente, y el legado de los macabeos sigue inspir\u00e1ndonos. Su llamamiento a defender lo que es justo, su dedicaci\u00f3n a sus creencias y su perdurable impacto en la tradici\u00f3n jud\u00eda resuenan en cada piedra e historia que transmitimos a la siguiente generaci\u00f3n. <\/p>\n","protected":false},"author":39,"featured_media":27204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[939,949,950,964,968,1018,1019],"tags":[],"class_list":["post-29866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-israel-es","category-ki-tisa-es","category-fe-y-espiritualidad","category-dios","category-los-cinco-libros-de-moises","category-educacion","category-januca"],"acf":[],"_links":{"self":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts\/29866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/comments?post=29866"}],"version-history":[{"count":3,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts\/29866\/revisions"}],"predecessor-version":[{"id":38187,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts\/29866\/revisions\/38187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/media\/27204"}],"wp:attachment":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/media?parent=29866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/categories?post=29866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/tags?post=29866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}