{"id":28433,"date":"2023-10-22T12:38:22","date_gmt":"2023-10-22T10:38:22","guid":{"rendered":"https:\/\/theisraelbible.com\/lucha-como-david-reflexiones-sobre-la-guerra\/"},"modified":"2025-07-02T08:44:32","modified_gmt":"2025-07-02T06:44:32","slug":"lucha-como-david-reflexiones-sobre-la-guerra","status":"publish","type":"post","link":"https:\/\/theisraelbible.com\/es\/lucha-como-david-reflexiones-sobre-la-guerra\/","title":{"rendered":"Lucha como David: Reflexiones sobre la guerra"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los atentados terroristas no son, por desgracia, algo nuevo para Israel. S\u00f3lo este a\u00f1o hemos sufrido demasiados, incluso antes del atroz atentado perpetrado por terroristas de Ham\u00e1s el 7 de octubre. Cada vez que un atentado sacude nuestra naci\u00f3n, sentimos rabia, nos sentimos devastados y nos preguntamos cu\u00e1nto m\u00e1s vamos a tener que soportar.  <\/p>\n\n<p class=\"wp-block-paragraph\">Contrarrestando la devastaci\u00f3n con consuelo y el odio con amor, la comunidad jud\u00eda entra en acci\u00f3n. Tras el asesinato de Lucy, Rina y Maia Dee hy \u00abd, por ejemplo, gente de todo Israel envi\u00f3 comida, dulces y amor; personas de todo el mundo tendieron la mano a la familia y se comprometieron a estudiar m\u00e1s la Biblia y a observar m\u00e1s fielmente la Tor\u00e1. \u00c9ste es el verdadero \u00abciclo de violencia\u00bb de Israel: los malvados terroristas \u00e1rabes asesinan a nuestros hijos, y los jud\u00edos de buen coraz\u00f3n responden colmando de amor a las v\u00edctimas.  <\/p>\n\n<p class=\"wp-block-paragraph\">Pero lo que suele ocurrir es que cuando termina <em>la shiva<\/em> (periodo de luto de siete d\u00edas), los funcionarios del gobierno y las celebridades jud\u00edas que visitaron a la familia afligida dirigen su atenci\u00f3n a otra parte. El resto de nosotros volvemos a nuestros desplazamientos, rezando para no volver a vivir este ciclo, pero sabiendo en el fondo de nuestro coraz\u00f3n que es casi seguro que lo viviremos. Nos decimos a nosotros mismos que debemos seguir adelante; \u00bfqu\u00e9 otra cosa podemos hacer hasta que llegue el Mes\u00edas?  <\/p>\n\n<p class=\"wp-block-paragraph\">En realidad, hay mucho que <em>podemos<\/em> hacer, si tan s\u00f3lo tenemos la voluntad. Algo debemos hacer si queremos romper este ciclo, \u00a1y ahora es el momento de actuar! <\/p>\n\n<p class=\"wp-block-paragraph\">S\u00ed, estamos rotos, y s\u00ed, nuestros corazones est\u00e1n llenos de amor y dolor por todas las familias de Israel en duelo y por aquellas cuyos seres queridos siguen desaparecidos. Pero tambi\u00e9n estamos enfadados. No, es m\u00e1s que ira; estamos furiosos.  <\/p>\n\n<p class=\"wp-block-paragraph\">Queremos que todos los viles yihadistas que asesinaron a 1.400 israel\u00edes inocentes mueran, y r\u00e1pido. \u00bfLas personas que ayudaron e instigaron a los terroristas, que les dieron apoyo y cobijo? Queremos que sientan el pu\u00f1o de hierro del pueblo de Israel. \u00bfY los cientos de miles de \u00e1rabes que aplaudieron este asesinato enfermo y malvado? Anhelamos el d\u00eda en que su alegr\u00eda se convierta en l\u00e1grimas, en que tiemblen ante nosotros y pidan clemencia. Y rezamos para que ese d\u00eda llegue pronto, para que nuestra generaci\u00f3n se asocie con Dios para \u00abvengar la sangre de sus siervos, descargar la venganza sobre sus enemigos y limpiar la tierra de su pueblo\u00bb<a href=\"https:\/\/theisraelbible.com\/bible\/deuteronomy-32\/#verse_43\">(Deuteronomio 32:43<\/a>). \u00abPadre nuestro, Rey nuestro, venga ante nuestros ojos la sangre derramada de Tus siervos\u00bb.      <\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/deuteronomy-32\/#verse_43\"><blockquote><p class=\"short_hebrew\">\u05d4\u05b7\u05e8\u05b0\u05e0\u05b4\u05d9\u05e0\u05d5\u05bc \u05d2\u05d5\u05b9\u05d9\u05b4\u05dd \u05e2\u05b7\u05de\u05bc\u05d5\u05b9 \u05db\u05bc\u05b4\u05d9 \u05d3\u05b7\u05dd\u05be\u05e2\u05b2\u05d1\u05b8\u05d3\u05b8\u05d9\u05d5 \u05d9\u05b4\u05e7\u05bc\u05d5\u05b9\u05dd \u05d5\u05b0\u05e0\u05b8\u05e7\u05b8\u05dd \u05d9\u05b8\u05e9\u05c1\u05b4\u05d9\u05d1 \u05dc\u05b0\u05e6\u05b8\u05e8\u05b8\u05d9\u05d5 \u05d5\u05b0\u05db\u05b4\u05e4\u05bc\u05b6\u05e8 \u05d0\u05b7\u05d3\u05b0\u05de\u05b8\u05ea\u05d5\u05b9 \u05e2\u05b7\u05de\u05bc\u05d5\u05b9\u05c3<\/p><p class=\"short_transliteration\">har-ni-NU go-YIM a-MO, KEE dam-a-va-DAV yi-KOM, v&#8217;-na-KAM ya-SHEEV l&#8217;-tza-RAV, v&#8217;-ki-PER ad-ma-TO a-MO. {P}<\/p><p class=\"short_translation\">\u00a1Oh naciones, aclamad a Su pueblo! Porque vengar\u00e1 la sangre de Sus siervos, Har\u00e1 venganza sobre Sus enemigos, Y limpiar\u00e1 la tierra de Su pueblo.<\/p><figcaption><cite>Deuteronomio 32:43<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">Ya puedo o\u00edr las protestas alarmadas de quienes encuentran inc\u00f3modo hablar de venganza. Como me escribi\u00f3 un rabino tras el asesinato de los Dees: \u00ab\u00bfNo somos mejores que nuestros enemigos? O somos un mont\u00f3n de animales que no son mejores que nuestros verdugos o no lo somos\u00bb. Parece ser un art\u00edculo de fe entre muchos l\u00edderes jud\u00edos que la acci\u00f3n contundente contra nuestros enemigos -el tipo de acci\u00f3n que har\u00e1 que los terroristas se lo piensen dos veces antes de atacarnos de nuevo- es de alg\u00fan modo inmoral o no jud\u00eda.  <\/p>\n\n<p class=\"wp-block-paragraph\">En su art\u00edculo cl\u00e1sico, <em>Kol Dodi Dofek<\/em>, el rabino Joseph B. Soloveitchik abord\u00f3 directamente estas preocupaciones. \u00abNo prestes atenci\u00f3n a las sugerencias sacarinas de conocidos asimilacionistas que&#8230; creen que siguen viviendo en Bialystok, Brest-Litovsk y Minsk del a\u00f1o 1905, y declaran abiertamente que la venganza est\u00e1 prohibida al pueblo jud\u00edo en cualquier lugar, en cualquier momento y bajo cualquier circunstancia. \u00ab\u00a1Vanidad de vanidades!\u00bb<a href=\"https:\/\/theisraelbible.com\/bible\/ecclesiastes-1\/#verse_2\">(Eclesiast\u00e9s 1:2<\/a>) La venganza est\u00e1 prohibida cuando es in\u00fatil, pero si con ello se incita a la autodefensa, es el derecho m\u00e1s elemental del hombre vengarse\u00bb. <\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/ecclesiastes-1\/#verse_2\"><blockquote><p class=\"short_hebrew\">\u05d4\u05b2\u05d1\u05b5\u05dc \u05d4\u05b2\u05d1\u05b8\u05dc\u05b4\u05d9\u05dd \u05d0\u05b8\u05de\u05b7\u05e8 \u05e7\u05b9\u05d4\u05b6\u05dc\u05b6\u05ea \u05d4\u05b2\u05d1\u05b5\u05dc \u05d4\u05b2\u05d1\u05b8\u05dc\u05b4\u05d9\u05dd \u05d4\u05b7\u05db\u05bc\u05b9\u05dc \u05d4\u05b8\u05d1\u05b6\u05dc\u05c3<\/p><p class=\"short_transliteration\">ha-VEL ha-va-LEEM a-MAR ko-HE-let ha-VEL ha-va-LEEM ha-KOL ha-VEL<\/p><p class=\"short_translation\">\u00a1Absoluta vanidad! \u2014dijo <em>Kohelet<\/em>\u2014 \u00a1Absoluta vanidad! Todo es vanidad.<\/p><figcaption><cite>Eclesiast\u00e9s 1:2<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">S\u00ed, debemos ser mejores que nuestros enemigos \u00e1rabes. Debemos ser mejores que ellos a la hora de defender ferozmente a nuestros hijos, pues el asesinato de un jud\u00edo es un asesinato de m\u00e1s. Debemos valorar la vida de nuestro pueblo m\u00e1s de lo que ellos valoran la suya. Y debemos ser mejores que nuestros enemigos a la hora de desarraigar y destruir el mal que infesta nuestra patria.   <\/p>\n\n<p class=\"wp-block-paragraph\">Tr\u00e1gicamente, nuestro gobierno ha olvidado hasta ahora las ense\u00f1anzas fundamentales del juda\u00edsmo, y familias inocentes est\u00e1n pagando el precio. Al responder d\u00e9bilmente al terror en el pasado, hemos enviado a nuestros enemigos un mensaje inaceptable: que estamos dispuestos a tolerar un cierto nivel de terror y que haremos malabarismos con el valor de las vidas jud\u00edas con otras consideraciones pol\u00edticas y militares. <\/p>\n\n<p class=\"wp-block-paragraph\">En otras palabras, el mero hecho de atrapar a los terroristas y llevarlos ante la \u00abjusticia\u00bb no impide futuros atentados. Una y otra vez, las IDF eliminan a los terroristas individuales que cometen estas atrocidades, pero no se disuade a los futuros terroristas. Los terroristas \u00e1rabes eligen conscientemente sacrificar sus propias vidas para asesinar a jud\u00edos por las recompensas que les esperan en el cielo y el beneficio econ\u00f3mico que recibir\u00e1n sus familias por su sacrificio. A trav\u00e9s del infame programa de la Autoridad Palestina \u00abPagar por matar\u00bb, la AP paga mensualmente a los familiares de los terroristas que mueren asesinando a jud\u00edos.   <\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfC\u00f3mo puede Israel detener el terror \u00e1rabe y proteger a su pueblo? Aprendiendo del ejemplo del rey David, que veng\u00f3 el asesinato de su familia y trajo la paz a Israel. <\/p>\n\n<p class=\"wp-block-paragraph\">Cuando David se convirti\u00f3 en fugitivo del celoso rey Sa\u00fal, llev\u00f3 a sus padres y hermanos ante el rey de Moab, para protegerlos de la ira de Sa\u00fal<a href=\"https:\/\/theisraelbible.com\/bible\/i-samuel-22\/#verse_1\">(I Samuel 22<\/a>). Tr\u00e1gicamente, los sabios explican que David no deber\u00eda haber confiado en los moabitas, sus parientes lejanos. \u00abEl rey de Moab mat\u00f3 [a la familia de David], y nadie escap\u00f3, salvo un hermano de David&#8230;\u00bb (N\u00fameros Rabba 14:1).  <\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/i-samuel-22\/#verse_1\"><blockquote><p class=\"short_hebrew\">\u05d5\u05b7\u05d9\u05bc\u05b5\u05dc\u05b6\u05da\u05b0 \u05d3\u05bc\u05b8\u05d5\u05b4\u05d3 \u05de\u05b4\u05e9\u05c1\u05bc\u05b8\u05dd \u05d5\u05b7\u05d9\u05bc\u05b4\u05de\u05bc\u05b8\u05dc\u05b5\u05d8 \u05d0\u05b6\u05dc\u05be\u05de\u05b0\u05e2\u05b8\u05e8\u05b7\u05ea \u05e2\u05b2\u05d3\u05bb\u05dc\u05bc\u05b8\u05dd \u05d5\u05b7\u05d9\u05bc\u05b4\u05e9\u05c1\u05b0\u05de\u05b0\u05e2\u05d5\u05bc \u05d0\u05b6\u05d7\u05b8\u05d9\u05d5 \u05d5\u05b0\u05db\u05b8\u05dc\u05be\u05d1\u05bc\u05b5\u05d9\u05ea \u05d0\u05b8\u05d1\u05b4\u05d9\u05d5 \u05d5\u05b7\u05d9\u05bc\u05b5\u05e8\u05b0\u05d3\u05d5\u05bc \u05d0\u05b5\u05dc\u05b8\u05d9\u05d5 \u05e9\u05c1\u05b8\u05de\u05bc\u05b8\u05d4\u05c3<\/p><p class=\"short_transliteration\">vai-YAY-lekh da-VID mi-SHAM vai-yi-ma-LET el me-a-RAT a-DU-lam vai-yish-MU e-KHAV v&#8217;-KOL bayt a-VEEV vai-YER-du e-LAV sha-MAH<\/p><p class=\"short_translation\"><em>David<\/em> parti\u00f3 de all\u00ed y escap\u00f3 a la cueva de <em>Adulam<\/em>; y cuando sus hermanos y toda la casa de su padre lo supieron, se unieron a \u00e9l all\u00ed.<\/p><figcaption><cite>Samuel 22:1<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">La madre, el padre y los hermanos de David fueron asesinados despiadadamente a sangre fr\u00eda. \u00bfC\u00f3mo respondi\u00f3 David? \u00bfFue comedido en su respuesta? \u00bfDistingui\u00f3 cuidadosamente entre la gran mayor\u00eda de moabitas \u00abinocentes\u00bb y los pocos malos que hab\u00edan asesinado a su familia?   <\/p>\n\n<p class=\"wp-block-paragraph\">No exactamente. \u00abE hiri\u00f3 a Moab, y los midi\u00f3 con un cordel, haci\u00e9ndolos tenderse en tierra; midi\u00f3 dos tramos de cordel para los que hab\u00edan de morir, y un tramo para los que hab\u00edan de ser perdonados. Y los moabitas se convirtieron en siervos de David, trayendo tributo\u00bb<a href=\"https:\/\/theisraelbible.com\/bible\/ii-samuel-8\/#verse_2\">(II Samuel 8:2<\/a>). En un breve vers\u00edculo, nos enteramos sin rodeos de que David humill\u00f3 y masacr\u00f3 a dos tercios del ej\u00e9rcito moabita, asegur\u00e1ndose de que los moabitas no volver\u00edan a perpetrar el terror contra el pueblo de Israel. David hizo insostenible el precio del terror, y as\u00ed ces\u00f3 el terror.   <\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/ii-samuel-8\/#verse_2\"><blockquote><p class=\"short_hebrew\">\u05d5\u05b7\u05d9\u05bc\u05b7\u05da\u05b0 \u05d0\u05b6\u05ea\u05be\u05de\u05d5\u05b9\u05d0\u05b8\u05d1 \u05d5\u05b7\u05d9\u05b0\u05de\u05b7\u05d3\u05bc\u05b0\u05d3\u05b5\u05dd \u05d1\u05bc\u05b7\u05d7\u05b6\u05d1\u05b6\u05dc \u05d4\u05b7\u05e9\u05c1\u05b0\u05db\u05bc\u05b5\u05d1 \u05d0\u05d5\u05b9\u05ea\u05b8\u05dd \u05d0\u05b7\u05e8\u05b0\u05e6\u05b8\u05d4 \u05d5\u05b7\u05d9\u05b0\u05de\u05b7\u05d3\u05bc\u05b5\u05d3 \u05e9\u05c1\u05b0\u05e0\u05b5\u05d9\u05be\u05d7\u05b2\u05d1\u05b8\u05dc\u05b4\u05d9\u05dd \u05dc\u05b0\u05d4\u05b8\u05de\u05b4\u05d9\u05ea \u05d5\u05bc\u05de\u05b0\u05dc\u05b9\u05d0 \u05d4\u05b7\u05d7\u05b6\u05d1\u05b6\u05dc \u05dc\u05b0\u05d4\u05b7\u05d7\u05b2\u05d9\u05d5\u05b9\u05ea \u05d5\u05b7\u05ea\u05bc\u05b0\u05d4\u05b4\u05d9 \u05de\u05d5\u05b9\u05d0\u05b8\u05d1 \u05dc\u05b0\u05d3\u05b8\u05d5\u05b4\u05d3 \u05dc\u05b7\u05e2\u05b2\u05d1\u05b8\u05d3\u05b4\u05d9\u05dd \u05e0\u05b9\u05e9\u05c2\u05b0\u05d0\u05b5\u05d9 \u05de\u05b4\u05e0\u05b0\u05d7\u05b8\u05d4\u05c3<\/p><p class=\"short_transliteration\">vai-YAKH et-MO-av va-y&#8217;-ma-DAY-dem ba-KHE-vel ha-sh&#8217;-KAYV ot-KHAM ar-TZA va-y&#8217;-ma-DAYD sh&#8217;-NAY-kha-va-LEEM l&#8217;-ha-MEET u-m&#8217;-LO ha-KHE-VEL l&#8217;-ha-cha-YOT va-TE-hee MO-av l&#8217;-da-VID la-a-va-DEEM nos-a-AY mi-n&#8217;-KHAH<\/p><p class=\"short_translation\">Tambi\u00e9n derrot\u00f3 a los moabitas. Los hizo acostarse en el suelo y los midi\u00f3 con una cuerda; midi\u00f3 dos longitudes de cuerda para los que iban a ser condenados a muerte, y una longitud para los que iban a ser perdonados. Y los moabitas se convirtieron en vasallos tributarios de <em>David<\/em>.<\/p><figcaption><cite>II - Samuel 8:2<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">\u00bfAprobaba Dios la dura represalia de David contra los moabitas? Dios no s\u00f3lo aprob\u00f3 las acciones de David, sino que le asegur\u00f3 la victoria: \u00abY Dios salv\u00f3 a David dondequiera que iba. Y rein\u00f3 David sobre todo Israel; y administr\u00f3 David justicia y caridad a todo su pueblo\u00bb<a href=\"https:\/\/theisraelbible.com\/bible\/ii-samuel-8\/#verse_14\">(II Samuel 8:14-15<\/a>). <\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/ii-samuel-8\/#verse_14\"><blockquote><p class=\"short_hebrew\">\u05d5\u05b7\u05d9\u05bc\u05b8\u05e9\u05c2\u05b6\u05dd \u05d1\u05bc\u05b6\u05d0\u05b1\u05d3\u05d5\u05b9\u05dd \u05e0\u05b0\u05e6\u05b4\u05d1\u05b4\u05d9\u05dd \u05d1\u05bc\u05b0\u05db\u05b8\u05dc\u05be\u05d0\u05b1\u05d3\u05d5\u05b9\u05dd \u05e9\u05c2\u05b8\u05dd \u05e0\u05b0\u05e6\u05b4\u05d1\u05b4\u05d9\u05dd \u05d5\u05b7\u05d9\u05b0\u05d4\u05b4\u05d9 \u05db\u05b8\u05dc\u05be\u05d0\u05b1\u05d3\u05d5\u05b9\u05dd \u05e2\u05b2\u05d1\u05b8\u05d3\u05b4\u05d9\u05dd \u05dc\u05b0\u05d3\u05b8\u05d5\u05b4\u05d3 \u05d5\u05b7\u05d9\u05bc\u05d5\u05b9\u05e9\u05c1\u05b7\u05e2 \u05d9\u05b0\u05d4\u05b9\u05d5\u05b8\u05d4 \u05d0\u05b6\u05ea\u05be\u05d3\u05bc\u05b8\u05d5\u05b4\u05d3 \u05d1\u05bc\u05b0\u05db\u05b9\u05dc \u05d0\u05b2\u05e9\u05c1\u05b6\u05e8 \u05d4\u05b8\u05dc\u05b8\u05da\u05b0\u05c3<\/p><p class=\"short_transliteration\">vai-YA-sem b&#8217;-e-DOM n&#8217;-tzi-VIM b&#8217;-KOL e-DOM sam n&#8217;-tzi-VIM va-Y&#8217;-hee kol e-DOM a-va-DEEM l&#8217;-da-VID vai-YO-sha a-do-NAI et da-VID b&#8217;-KOL a-SHER ha-LAKH<\/p><p class=\"short_translation\">Estableci\u00f3 guarniciones en Edom, estableci\u00f3 guarniciones en todo Edom, y todos los edomitas se convirtieron en vasallos de <em>David<\/em>. <em>Hashem<\/em> dio a <em>David<\/em> la victoria dondequiera que iba.<\/p><figcaption><cite>II - Samuel 8:14<\/cite><\/figcaption><\/blockquote><\/a><\/div><div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/ii-samuel-8\/#verse_15\"><blockquote><p class=\"short_hebrew\">\u05d5\u05b7\u05d9\u05bc\u05b4\u05de\u05b0\u05dc\u05b9\u05da\u05b0 \u05d3\u05bc\u05b8\u05d5\u05b4\u05d3 \u05e2\u05b7\u05dc\u05be\u05db\u05bc\u05b8\u05dc\u05be\u05d9\u05b4\u05e9\u05c2\u05b0\u05e8\u05b8\u05d0\u05b5\u05dc \u05d5\u05b7\u05d9\u05b0\u05d4\u05b4\u05d9 \u05d3\u05b8\u05d5\u05b4\u05d3 \u05e2\u05b9\u05e9\u05c2\u05b6\u05d4 \u05de\u05b4\u05e9\u05c1\u05b0\u05e4\u05bc\u05b8\u05d8 \u05d5\u05bc\u05e6\u05b0\u05d3\u05b8\u05e7\u05b8\u05d4 \u05dc\u05b0\u05db\u05b8\u05dc\u05be\u05e2\u05b7\u05de\u05bc\u05d5\u05b9\u05c3<\/p><p class=\"short_transliteration\">va-yim-LOKH da-VID al kol yis-ra-AYL vai-HEE da-VID o-SEH mish-PAT utz-da-KAH l&#8217;-khol a-MO<\/p><p class=\"short_translation\"><em>David<\/em> rein\u00f3 sobre todo <em>Yisrael<\/em>, y <em>David<\/em> ejecut\u00f3 verdadera justicia entre todo su pueblo.<\/p><figcaption><cite>II - Samuel 8:15<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">Cada ma\u00f1ana, los jud\u00edos tradicionales recuerdan que Dios desea la destrucci\u00f3n del mal. En palabras de David \u00abExulten los fieles&#8230; con altas alabanzas a Dios en sus gargantas y espadas de dos filos en sus manos, para ejecutar venganza sobre las naciones y castigos sobre los pueblos&#8230; para ejecutar la condena decretada contra ellos. Esta es la gloria de todos Sus fieles. Aleluya!\u00bb<a href=\"https:\/\/theisraelbible.com\/bible\/psalms-149\/#verse_6\">(Salmos 149:6-7,9<\/a>). <\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/psalms-149\/#verse_6\"><blockquote><p class=\"short_hebrew\">\u05e8\u05d5\u05b9\u05de\u05b0\u05de\u05d5\u05b9\u05ea \u05d0\u05b5\u05dc \u05d1\u05bc\u05b4\u05d2\u05b0\u05e8\u05d5\u05b9\u05e0\u05b8\u05dd \u05d5\u05b0\u05d7\u05b6\u05e8\u05b6\u05d1 \u05e4\u05bc\u05b4\u05d9\u05e4\u05b4\u05d9\u05bc\u05d5\u05b9\u05ea \u05d1\u05bc\u05b0\u05d9\u05b8\u05d3\u05b8\u05dd\u05c3<\/p><p class=\"short_transliteration\">ro-m&#8217;-MOT AYL big-ro-NAM v&#8217;-KHE-rev pee-fi-YOT b&#8217;-ya-DAM<\/p><p class=\"short_translation\">con himnos a <em>Hashem<\/em> en sus gargantas y espadas de dos filos en sus manos,<\/p><figcaption><cite>Salmos 149:6<\/cite><\/figcaption><\/blockquote><\/a><\/div><div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/psalms-149\/#verse_7\"><blockquote><p class=\"short_hebrew\">\u05dc\u05b7\u05e2\u05b2\u05e9\u05c2\u05d5\u05b9\u05ea \u05e0\u05b0\u05e7\u05b8\u05de\u05b8\u05d4 \u05d1\u05bc\u05b7\u05d2\u05bc\u05d5\u05b9\u05d9\u05b4\u05dd \u05ea\u05bc\u05d5\u05b9\u05db\u05b5\u05d7\u05b9\u05ea \u05d1\u05bc\u05b7\u05dc\u05be\u05d0\u05bb\u05de\u05bc\u05b4\u05d9\u05dd\u05c3<\/p><p class=\"short_transliteration\">la-a-SOT n&#8217;-KA-mah ba-go-YIM to-KHE-khot bal-u-MEEM<\/p><p class=\"short_translation\">para imponer retribuci\u00f3n a las naciones, castigo a los pueblos,<\/p><figcaption><cite>Salmos 149:7<\/cite><\/figcaption><\/blockquote><\/a><\/div><div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/psalms-149\/#verse_9\"><blockquote><p class=\"short_hebrew\">\u05dc\u05b7\u05e2\u05b2\u05e9\u05c2\u05d5\u05b9\u05ea \u05d1\u05bc\u05b8\u05d4\u05b6\u05dd \u05de\u05b4\u05e9\u05c1\u05b0\u05e4\u05bc\u05b8\u05d8 \u05db\u05bc\u05b8\u05ea\u05d5\u05bc\u05d1 \u05d4\u05b8\u05d3\u05b8\u05e8 \u05d4\u05d5\u05bc\u05d0 \u05dc\u05b0\u05db\u05b8\u05dc\u05be\u05d7\u05b2\u05e1\u05b4\u05d9\u05d3\u05b8\u05d9\u05d5 \u05d4\u05b7\u05dc\u05b0\u05dc\u05d5\u05bc\u05be\u05d9\u05b8\u05d4\u05bc\u05c3<\/p><p class=\"short_transliteration\">la-a-SOT ba-HEM mish-PAT ka-TOV ha-DAR HU l&#8217;-KOL cha-see-DAV hal-lu-YAH. {P}<\/p><p class=\"short_translation\">ejecutando la condena decretada contra ellos. Esta es la gloria de todos Sus fieles. Aleluya.<\/p><figcaption><cite>Salmos 149:9<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">Durante 3.000 a\u00f1os, nuestro pueblo ha rezado como David, susurrando las bellas palabras de los Salmos durante los d\u00edas m\u00e1s oscuros de nuestro exilio. Ya es hora de que aprendamos tambi\u00e9n a luchar como \u00e9l. <\/p>\n\n<p class=\"wp-block-paragraph\">David no fue pasivo. David no se sent\u00f3 a esperar a que Dios actuara, a que un terremoto se tragara a sus enemigos. David no esper\u00f3 a una futura era mesi\u00e1nica, en la que Dios destruir\u00eda milagrosamente a los enemigos de Israel. David comprendi\u00f3 que el pueblo de Israel deb\u00eda asociarse con Dios para llevar a cabo Su voluntad, que nosotros deb\u00edamos ser el filo de la espada de Dios.   <\/p>\n\n<p class=\"wp-block-paragraph\">David no luch\u00f3 contra los terroristas que asolaban a su pueblo con medias tintas, ni tuvo miedo de castigar a los \u00abciviles inocentes\u00bb que apoyaban a los terroristas que asesinaron a su familia. \u00abPersegu\u00ed a mis enemigos y los alcanc\u00e9; no retroced\u00ed hasta consumirlos por completo\u00bb<a href=\"https:\/\/theisraelbible.com\/bible\/psalms-18\/#verse_38\">(Salmos 18:38<\/a>). <\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/psalms-18\/#verse_38\"><blockquote><p class=\"short_hebrew\">\u05d0\u05b6\u05e8\u05b0\u05d3\u05bc\u05d5\u05b9\u05e3 \u05d0\u05d5\u05b9\u05d9\u05b0\u05d1\u05b7\u05d9 \u05d5\u05b0\u05d0\u05b7\u05e9\u05c2\u05bc\u05b4\u05d9\u05d2\u05b5\u05dd \u05d5\u05b0\u05dc\u05b9\u05d0\u05be\u05d0\u05b8\u05e9\u05c1\u05d5\u05bc\u05d1 \u05e2\u05b7\u05d3\u05be\u05db\u05bc\u05b7\u05dc\u05bc\u05d5\u05b9\u05ea\u05b8\u05dd\u05c3<\/p><p class=\"short_transliteration\">er-DOf o-Y&#8217;-vai v&#8217;-a-see-GEM, v&#8217;-LO-a-SHUv ad-KA-lo-TAM<\/p><p class=\"short_translation\">Persegu\u00ed a mis enemigos y los alcanc\u00e9; no volv\u00ed atr\u00e1s hasta que los destru\u00ed.<\/p><figcaption><cite>Salmos 18:38<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">A David no le preocupaba la opini\u00f3n mundial ni las condenas farisaicas de otros pa\u00edses. No se avergonzaba de buscar venganza. \u00abOh Dios, r\u00f3mpeles los dientes en la boca; r\u00f3mpeles los colmillos a los leones, Dios&#8230; El justo se alegrar\u00e1 cuando vea la venganza; ba\u00f1ar\u00e1 sus pies en la sangre de los malvados. Los hombres dir\u00e1n: 'Hay, pues, recompensa para el justo; hay, en verdad, justicia divina en la tierra'\u00bb.<a href=\"https:\/\/theisraelbible.com\/bible\/psalms-58\/#verse_7\">(Salmos 58:7,11-12<\/a>).  <\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/psalms-58\/#verse_7\"><blockquote><p class=\"short_hebrew\">\u05d0\u05b1\u200d\u05dc\u05b9\u05d4\u05b4\u05d9\u05dd \u05d4\u05b2\u05e8\u05b8\u05e1\u05be\u05e9\u05c1\u05b4\u05e0\u05bc\u05b5\u05d9\u05de\u05d5\u05b9 \u05d1\u05bc\u05b0\u05e4\u05b4\u05d9\u05de\u05d5\u05b9 \u05de\u05b7\u05dc\u05b0\u05ea\u05bc\u05b0\u05e2\u05d5\u05b9\u05ea \u05db\u05bc\u05b0\u05e4\u05b4\u05d9\u05e8\u05b4\u05d9\u05dd \u05e0\u05b0\u05ea\u05b9\u05e5 \u05d9\u05b0\u05d4\u05b9\u05d5\u05b8\u05d4\u05c3<\/p><p class=\"short_transliteration\">E-lo-HIM ha-ROS shi-NEE-mo b&#8217;-fi-MO mal-t&#8217;-OT k&#8217;-fi-REEM n&#8217;-TOT a-do-NAI<\/p><p class=\"short_translation\">Oh <em>Hashem<\/em>, aplasta sus dientes en su boca; destroza los colmillos de los leones, <em>Hashem<\/em>;<\/p><figcaption><cite>Salmos 58:7<\/cite><\/figcaption><\/blockquote><\/a><\/div><div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/psalms-58\/#verse_11\"><blockquote><p class=\"short_hebrew\">\u05d9\u05b4\u05e9\u05c2\u05b0\u05de\u05b7\u05d7 \u05e6\u05b7\u05d3\u05bc\u05b4\u05d9\u05e7 \u05db\u05bc\u05b4\u05d9\u05be\u05d7\u05b8\u05d6\u05b8\u05d4 \u05e0\u05b8\u05e7\u05b8\u05dd \u05e4\u05bc\u05b0\u05e2\u05b8\u05de\u05b8\u05d9\u05d5 \u05d9\u05b4\u05e8\u05b0\u05d7\u05b7\u05e5 \u05d1\u05bc\u05b0\u05d3\u05b7\u05dd \u05d4\u05b8\u05e8\u05b8\u05e9\u05c1\u05b8\u05e2\u05c3<\/p><p class=\"short_transliteration\">YIS-makh tza-DEEK kee-cha-ZAH na-KAM pe-a-MAV yir-KHATZ b&#8217;-DAM ha-ra-SHA<\/p><p class=\"short_translation\">El hombre justo se regocijar\u00e1 cuando vea la venganza; ba\u00f1ar\u00e1 sus pies en la sangre de los malvados.<\/p><figcaption><cite>Salmos 58:11<\/cite><\/figcaption><\/blockquote><\/a><\/div><div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/psalms-58\/#verse_12\"><blockquote><p class=\"short_hebrew\">\u05d5\u05b0\u05d9\u05b9\u05d0\u05de\u05b7\u05e8 \u05d0\u05b8\u05d3\u05b8\u05dd \u05d0\u05b7\u05da\u05b0\u05be\u05e4\u05bc\u05b0\u05e8\u05b4\u05d9 \u05dc\u05b7\u05e6\u05bc\u05b7\u05d3\u05bc\u05b4\u05d9\u05e7 \u05d0\u05b7\u05da\u05b0 \u05d9\u05b5\u05e9\u05c1\u05be\u05d0\u05b1\u05dc\u05b9\u05d4\u05b4\u05d9\u05dd \u05e9\u05c1\u05b9\u05e4\u05b0\u05d8\u05b4\u05d9\u05dd \u05d1\u05bc\u05b8\u05d0\u05b8\u05e8\u05b6\u05e5\u05c3<\/p><p class=\"short_transliteration\">v&#8217;-yo-MAR a-DAM akh p&#8217;-REE la-tza-DEEK akh YAYSH e-lo-HEEM sho-f&#8217;-TEEM ba-a-RETZ<\/p><p class=\"short_translation\">Los hombres dir\u00e1n: \u00abEntonces, hay una recompensa para los justos; de hecho, hay justicia divina en la tierra.\u00bb<\/p><figcaption><cite>Salmos 58:12<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">Las acciones de David fueron duras, pero morales y eficaces. Al responder en\u00e9rgicamente a quienes asesinaban a su familia, David inaugur\u00f3 una era de paz sin precedentes, que permiti\u00f3 a su hijo Salom\u00f3n construir el Templo de Dios en Jerusal\u00e9n. Lo m\u00e1s importante de todo es que David nos dio el manual de la redenci\u00f3n, si estamos dispuestos a utilizarlo.  <\/p>\n\n<p class=\"wp-block-paragraph\">La guerra no es agradable; en este mundo imperfecto, inevitablemente sufren personas inocentes. Pero la responsabilidad de un gobierno, ante todo, es defender a su propio pueblo. Entre octubre de 2001 y junio de 2003, Estados Unidos mat\u00f3 involuntariamente a unos 3.500 civiles afganos mediante bombardeos a\u00e9reos durante la Operaci\u00f3n Libertad Duradera. Las muertes de civiles son tr\u00e1gicas, pero el mundo libre comprendi\u00f3 que, tras el asesinato de ciudadanos estadounidenses el 11-S, Estados Unidos ten\u00eda que hacer todo lo que estuviera en su mano para defender a su pueblo. S\u00ed, debemos tener un nivel de exigencia superior al de los terroristas, pero no un nivel imposiblemente elevado que limite nuestra capacidad de defender a nuestro pueblo.    <\/p>\n\n<p class=\"wp-block-paragraph\">\u00abQue sea bueno a Tus ojos bendecir a Tu pueblo Israel en todo tiempo, en toda hora, con Tu paz\u00bb. Durante miles de a\u00f1os, nuestro pueblo ha anhelado la paz, y no dejaremos de rezar por la paz hasta que venga el Mes\u00edas. Pero el amor por s\u00ed solo no detendr\u00e1 a los terroristas. El camino hacia la paz no estar\u00e1 sembrado de rosas, sino a trav\u00e9s de la fe en Dios y la fortaleza para hacer que nuestros enemigos paguen por sus pecados. Como David, no debemos olvidar, y no nos atrevemos a perdonar.    <\/p>\n\n<p class=\"wp-block-paragraph\">\u00a1Ahora es el momento de luchar como David! Que Dios nos conceda \u00e9xito contra nuestros enemigos y protecci\u00f3n para nuestros soldados, civiles y rehenes, y que nos bendiga con la paz eterna. <\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los atentados terroristas no son, por desgracia, algo nuevo para Israel. S\u00f3lo este a\u00f1o hemos sufrido demasiados, incluso antes del atroz atentado perpetrado por terroristas de Ham\u00e1s el 7 de octubre. Cada vez que un atentado sacude nuestra naci\u00f3n, sentimos rabia, nos sentimos devastados y nos preguntamos cu\u00e1nto m\u00e1s vamos a tener que soportar. Contrarrestando [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":24519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[929,939,955,971,1001,1121],"tags":[1064,1156,1296,5555,5742,5743],"class_list":["post-28433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salmos","category-israel-es","category-justicia","category-deuteronomio","category-samuel-es","category-eclesiastes","tag-etica-biblica","tag-fin-de-los-dias","tag-rey-manases","tag-venganza-divina","tag-terror-y-seguridad","tag-politica-moderna-de-israel"],"acf":[],"_links":{"self":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts\/28433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/comments?post=28433"}],"version-history":[{"count":2,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts\/28433\/revisions"}],"predecessor-version":[{"id":35249,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts\/28433\/revisions\/35249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/media\/24519"}],"wp:attachment":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/media?parent=28433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/categories?post=28433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/tags?post=28433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}