{"id":27982,"date":"2023-03-19T13:21:28","date_gmt":"2023-03-19T11:21:28","guid":{"rendered":"https:\/\/theisraelbible.com\/el-mes-de-la-redencion\/"},"modified":"2025-05-09T17:55:35","modified_gmt":"2025-05-09T15:55:35","slug":"el-mes-de-la-redencion","status":"publish","type":"post","link":"https:\/\/theisraelbible.com\/es\/el-mes-de-la-redencion\/","title":{"rendered":"El Mes de la Redenci\u00f3n"},"content":{"rendered":"<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/exodus-12\/#verse_1\"><blockquote><p class=\"short_hebrew\">\u05d5\u05b7\u05d9\u05bc\u05b9\u05d0\u05de\u05b6\u05e8 \u05d9\u05b0\u05d4\u05b9\u05d5\u05b8\u05d4 \u05d0\u05b6\u05dc\u05be\u05de\u05b9\u05e9\u05c1\u05b6\u05d4 \u05d5\u05b0\u05d0\u05b6\u05dc\u05be\u05d0\u05b7\u05d4\u05b2\u05e8\u05b9\u05df \u05d1\u05bc\u05b0\u05d0\u05b6\u05e8\u05b6\u05e5 \u05de\u05b4\u05e6\u05b0\u05e8\u05b7\u05d9\u05b4\u05dd \u05dc\u05b5\u05d0\u05de\u05b9\u05e8\u05c3<\/p><p class=\"short_transliteration\">va-YO-mer a-do-NAI el mo-SHEH v&#8217;-el a-ha-RON b&#8217;-E-retz mitz-RA-yim lay-MOR<\/p><p class=\"short_translation\"><em>Hashem<\/em> dijo a <em>Moshe<\/em> y <em>Aharon<\/em> en la tierra de Egipto:<\/p><figcaption><cite>\u00c9xodo 12:1<\/cite><\/figcaption><\/blockquote><\/a><\/div><div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/exodus-12\/#verse_2\"><blockquote><p class=\"short_hebrew\">\u05d4\u05b7\u05d7\u05b9\u05d3\u05b6\u05e9\u05c1 \u05d4\u05b7\u05d6\u05bc\u05b6\u05d4 \u05dc\u05b8\u05db\u05b6\u05dd \u05e8\u05b9\u05d0\u05e9\u05c1 \u05d7\u05b3\u05d3\u05b8\u05e9\u05c1\u05b4\u05d9\u05dd \u05e8\u05b4\u05d0\u05e9\u05c1\u05d5\u05b9\u05df \u05d4\u05d5\u05bc\u05d0 \u05dc\u05b8\u05db\u05b6\u05dd \u05dc\u05b0\u05d7\u05b8\u05d3\u05b0\u05e9\u05c1\u05b5\u05d9 \u05d4\u05b7\u05e9\u05c1\u05bc\u05b8\u05e0\u05b8\u05d4\u05c3<\/p><p class=\"short_transliteration\">ha-KHO-desh ha-ZEH la-KHEM ROSH kho-da-SHEEM ri-SHON HU la-KHEM l&#8217;-khod-SHAY ha-sha-NAH<\/p><p class=\"short_translation\">Este mes ser\u00e1 para ustedes el comienzo de los meses; ser\u00e1 el primero de los meses del a\u00f1o para ustedes.<\/p><figcaption><cite>\u00c9xodo 12:2<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">Este primer mes del calendario hebreo se conoce actualmente como <em>Nis\u00e1n<\/em> (\u05e0\u05b4\u05d9\u05e1\u05b8\u05df), nombre adoptado durante el exilio babil\u00f3nico. En la Biblia, se llama \u00abel mes de <em>Aviv<\/em>\u00ab. <\/p>\n\n<p class=\"wp-block-paragraph\"><em>\u00abAviv<\/em>\u00ab, palabra hebrea que significa primavera, es el nombre b\u00edblico hebreo de la cebada cuando est\u00e1 completamente madura y verde, mencionada por primera vez en <a href=\"https:\/\/theisraelbible.com\/bible\/exodus-9\/#verse_31\">\u00c9xodo 9:31<\/a>. Pasea por los campos de cebada israel\u00edes este mes y ver\u00e1s por qu\u00e9. <\/p>\n\n<p class=\"wp-block-paragraph\"><em>Nis\u00e1n<\/em> es muy querido por el Pueblo de Israel porque es el mes en el que tuvo lugar el \u00c9xodo de Egipto, como dice:  <\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/exodus-13\/#verse_4\"><blockquote><p class=\"short_hebrew\">\u05d4\u05b7\u05d9\u05bc\u05d5\u05b9\u05dd \u05d0\u05b7\u05ea\u05bc\u05b6\u05dd \u05d9\u05b9\u05e6\u05b0\u05d0\u05b4\u05d9\u05dd \u05d1\u05bc\u05b0\u05d7\u05b9\u05d3\u05b6\u05e9\u05c1 \u05d4\u05b8\u05d0\u05b8\u05d1\u05b4\u05d9\u05d1\u05c3<\/p><p class=\"short_transliteration\">ha-YOM a-TEM yo-tz&#8217;-EEM b&#8217;-KHO-desh ha-a-VEEV<\/p><p class=\"short_translation\">Salen libres en este d\u00eda, en el mes de Abib.<\/p><figcaption><cite>\u00c9xodo 13:4<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">Conmemoramos este acontecimiento cada a\u00f1o durante la fiesta de la Pascua, en el mes de <em>Nis\u00e1n<\/em>.<\/p>\n\n<p class=\"wp-block-paragraph\">Esto suscita la pregunta: \u00bfPor qu\u00e9 eligi\u00f3 Dios este mes de <em>Aviv\/Nis\u00e1n<\/em> como mes de la redenci\u00f3n? No s\u00f3lo Dios redimi\u00f3 al pueblo jud\u00edo de Egipto en este mes, sino que, seg\u00fan la tradici\u00f3n jud\u00eda, la redenci\u00f3n final tambi\u00e9n tendr\u00e1 lugar en <em>Nis\u00e1n, <\/em>\u00bfpor qu\u00e9? <\/p>\n\n<p class=\"wp-block-paragraph\"><em>Aviv\/Nis\u00e1n<\/em> es el primer mes de la primavera, cuando el mundo natural vuelve a la vida. Hoy lo notamos sobre todo por los brotes y las hojas que brotan en los \u00e1rboles locales. Pero los campesinos de los tiempos b\u00edblicos ve\u00edan la llegada de la primavera por las gordas y verdes espigas de cebada de sus campos. Y al igual que Dios renueva y da nueva energ\u00eda al mundo f\u00edsico durante este mes, tambi\u00e9n hace lo mismo con la dimensi\u00f3n espiritual de la vida.   <\/p>\n\n<p class=\"wp-block-paragraph\">Para el Pueblo de Israel, no ha habido mayor refresco espiritual que el \u00c9xodo de Egipto. El mundo nunca hab\u00eda visto, ni ha visto desde entonces, un acontecimiento semejante. <\/p>\n\n<p class=\"wp-block-paragraph\">\u00a1Imagina ser testigo de c\u00f3mo diez plagas sobrenaturales destruyen el reino m\u00e1s poderoso del mundo!  <\/p>\n\n<p class=\"wp-block-paragraph\">Imagina a millones de antiguos esclavos, todos de una misma familia, abandonando su pa\u00eds de acogida con una riqueza incre\u00edble. \u00a1Y a plena luz del d\u00eda! <\/p>\n\n<p class=\"wp-block-paragraph\">El pueblo jud\u00edo era por fin libre para adorar al Dios \u00danico, recibir la palabra de Dios en el monte Sina\u00ed y regresar a la tierra de Dios, Israel. Fue el nacimiento de una naci\u00f3n que convertir\u00eda un mundo hundido en la idolatr\u00eda en un mundo de conciencia de Dios y moral divina. \u00a1Era primavera en el mundo de Dios!  <\/p>\n\n<p class=\"wp-block-paragraph\">Pero el trabajo no hab\u00eda hecho m\u00e1s que empezar. Tras muchos altibajos a lo largo de los milenios, el Pueblo de Israel ha vuelto milagrosamente a su tierra. Pero aunque gran parte del mundo adora ahora al \u00danico Dios, sigue habiendo una tremenda oscuridad espiritual en el mundo.  <br\/><br\/>Al igual que en Egipto, nuestro mundo se volver\u00e1 tan fr\u00edo y oscuro que muchos perder\u00e1n la esperanza de la redenci\u00f3n. Ser\u00e1 otro invierno espiritual. <br\/><br\/>Pero al final, Dios cumplir\u00e1 sus promesas. Una vez m\u00e1s, <em>Nis\u00e1n,<\/em> el comienzo de la primavera, traer\u00e1 la renovaci\u00f3n espiritual y el renacimiento del pueblo jud\u00edo en forma de la redenci\u00f3n final.   <\/p>\n\n<p class=\"wp-block-paragraph\">\u00bfSer\u00e1 este a\u00f1o? \u00bfEl a\u00f1o que viene? \u00bfDentro de varias d\u00e9cadas? No lo sabemos, pero tenemos fe en que llegar\u00e1.   <\/p>\n\n<p class=\"wp-block-paragraph\">Hasta entonces, aprovecha el poder espiritual del mes de <em>Nis\u00e1n<\/em>: disfruta de la libertad de adorar a Dios, de expresar tu fe y de vivir tu vida al m\u00e1ximo, y anticipa las promesas b\u00edblicas de Dios de que el mundo ser\u00e1 redimido.<\/p>\n<div class=\"wp-block-chapter-verse-content\"><a href=\"https:\/\/theisraelbible.com\/es\/bible\/zechariah-14\/#verse_9\"><blockquote><p class=\"short_hebrew\">\u05d5\u05b0\u05d4\u05b8\u05d9\u05b8\u05d4 \u05d9\u05b0\u05d4\u05b9\u05d5\u05b8\u05d4 \u05dc\u05b0\u05de\u05b6\u05dc\u05b6\u05da\u05b0 \u05e2\u05b7\u05dc\u05be\u05db\u05bc\u05b8\u05dc\u05be\u05d4\u05b8\u05d0\u05b8\u05e8\u05b6\u05e5 \u05d1\u05bc\u05b7\u05d9\u05bc\u05d5\u05b9\u05dd \u05d4\u05b7\u05d4\u05d5\u05bc\u05d0 \u05d9\u05b4\u05d4\u05b0\u05d9\u05b6\u05d4 \u05d9\u05b0\u05d4\u05b9\u05d5\u05b8\u05d4 \u05d0\u05b6\u05d7\u05b8\u05d3 \u05d5\u05bc\u05e9\u05c1\u05b0\u05de\u05d5\u05b9 \u05d0\u05b6\u05d7\u05b8\u05d3\u05c3<\/p><p class=\"short_transliteration\">v&#8217;-ha-YAH a-do-NAI l&#8217;-ME-lekh al-KOL ha-A-retz ba-YOM ha-HU yi-HE-yah a-do-NAI e-KHAD u-sh&#8217;-MO e-KHAD<\/p><p class=\"short_translation\">Y <em>Hashem<\/em> ser\u00e1 rey sobre toda la tierra; en ese d\u00eda habr\u00e1 un solo <em>Hashem<\/em> con un solo nombre.<\/p><figcaption><cite>Zacar\u00edas 14:9<\/cite><\/figcaption><\/blockquote><\/a><\/div>\n<p class=\"wp-block-paragraph\">\u00a1Feliz <em>Nisan<\/em>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este primer mes del calendario hebreo se conoce actualmente como Nis\u00e1n (\u05e0\u05b4\u05d9\u05e1\u05b8\u05df), nombre adoptado durante el exilio babil\u00f3nico. En la Biblia, se llama \u00abel mes de Aviv\u00ab. \u00abAviv\u00ab, palabra hebrea que significa primavera, es el nombre b\u00edblico hebreo de la cebada cuando est\u00e1 completamente madura y verde, mencionada por primera vez en \u00c9xodo 9:31. Pasea [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":24339,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[936,942,1021,1047,1143],"tags":[1069,1076,2189,4802,4803,4804],"class_list":["post-27982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-redencion","category-exodo","category-zacarias","category-pascua-judia","category-nisan-es","tag-faraon","tag-simbolismo-biblico","tag-el-momento-divino","tag-la-division-del-mar-es","tag-simbolismo-de-la-primavera","tag-calendario-hebreo"],"acf":[],"_links":{"self":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts\/27982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/comments?post=27982"}],"version-history":[{"count":1,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts\/27982\/revisions"}],"predecessor-version":[{"id":27984,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/posts\/27982\/revisions\/27984"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/media\/24339"}],"wp:attachment":[{"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/media?parent=27982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/categories?post=27982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theisraelbible.com\/es\/wp-json\/wp\/v2\/tags?post=27982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}